{"id":25909,"date":"2025-06-05T12:44:39","date_gmt":"2025-06-05T10:44:39","guid":{"rendered":"https:\/\/acpau.org\/?p=25909"},"modified":"2026-04-04T19:44:51","modified_gmt":"2026-04-04T17:44:51","slug":"entrevista-a-la-activista-iman-hammouri","status":"publish","type":"post","link":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/","title":{"rendered":"\u201cEn Gaza a\u00fan organizamos actividades art\u00edsticas para que ni\u00f1as y j\u00f3venes puedan contar con un espacio seguro\u201d"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-right:0px;--awb-padding-bottom:0px;--awb-padding-left:0px;--awb-margin-top:60px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:10px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><p><em>Texto e im\u00e1genes: Aitor Molina y Ivonne Morales<\/em><\/p>\n<h6 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"22\" data-lineheight=\"33px\">Entrevista a Iman Hammouri, activista social y defensora de los derechos culturales<\/h6>\n<p>Iman Hammouri (Palestina, 1969) es una activista social y defensora de los derechos culturales con una dilatada experiencia en diferentes proyectos culturales y sociales. Actualmente es directora del Popular Art Centre (Ramallah, Palestina) y cofundadora de la Palestinian Performing Arts Network. A lo largo de su carrera ha realizado ponencias a nivel internacional sobre el papel de la sociedad civil en el arte y la cultura; siendo elegida miembro de diferentes jurados para reconocer los logros art\u00edsticos y culturales.<\/p>\n<p>Estos d\u00edas, Iman ha visitado Barcelona invitada por la Associaci\u00f3 Catalana per la Pau, en el marco del proyecto \u201c<a href=\"https:\/\/acpau.org\/es\/som-constructores\/\" target=\"_blank\" rel=\"noopener\">Som Constructores<\/a>\u201d, para establecer puentes y colaboraciones entre las entidades culturales catalanas y palestinas. Pero este viaje no lo ha realizado sola, junto a ella tambi\u00e9n ha viajado el bailar\u00edn y core\u00f3grafo, Sharaf Darzaid, que present\u00f3 su espect\u00e1culo \u201cLove in Times of Apartheid\u201d en la Fira Mediterr\u00e1nia de Manresa e imparti\u00f3 diferentes talleres y clases magistrales por todo el territorio.<\/p>\n<p>Tanto Iman (directora) como Sharaf (bailar\u00edn y docente), forman parte del <a href=\"https:\/\/www.popularartcentre.org\/index.php\" target=\"_blank\" rel=\"noopener\">Popular Art Centre<\/a> (PAC), una organizaci\u00f3n sin \u00e1nimo de lucro fundada en Palestina en 1987 con el objetivo de difundir las artes creativas y culturales en diversos sectores de la sociedad palestina con el fin de mantener y preservar la herencia cultural, proteger la identidad nacional y reivindicar esta identidad palestina como herramienta de resistencia contra la ocupaci\u00f3n israel\u00ed.<\/p>\n<p>Desde el 1993, siempre que el contexto lo ha permitido, ha organizado el <a href=\"https:\/\/www.popularartcentre.org\/index.php?page=section&amp;pid=7&amp;section_parent=0&amp;catid=3\" target=\"_blank\" rel=\"noopener\">Palestine International Festival for Dance and Music<\/a>, donde han participado artistas reconocidos mundialmente como STOMP (Reino Unido), Gipsy Kings (Francia), Inti Illimani (Chile), Fire of Anatolia (Turqu\u00eda), etc.<\/p>\n<p><strong>Buenos d\u00edas Iman. En primer lugar, cu\u00e9ntanos un poco c\u00f3mo comenzaste a interesarte en el mundo de la cultura y c\u00f3mo llegaste a presidir el Popular Art Centre en Palestina.<\/strong><\/p>\n<p>En realidad desde peque\u00f1a he realizado actividades art\u00edsticas, comenc\u00e9 como bailarina en un grupo de danza y cuando estaba en la universidad hice voluntariado en el Palestinian International Festival que el Popular Art Centre sol\u00eda organizar y donde tra\u00edan a prestigiosos artistas de todo el mundo. Unos a\u00f1os despu\u00e9s, cuando acab\u00e9 mi m\u00e1ster, me llamaron y me preguntaron:\u00a0\u201c\u00bfTe gustar\u00eda dirigir el centro?\u201d\u00a0Entonces pens\u00e9, \u201cme encanta el centro y no me gustar\u00eda verlo cerrado\u201d. As\u00ed que dije: \u201cS\u00ed, aceptar\u00e9 este desaf\u00edo\u201d.<\/p>\n<p>Pero cuando comenc\u00e9 a dirigirlo estall\u00f3 la Segunda Intifada. As\u00ed que fue un desaf\u00edo doble, no s\u00f3lo por la deuda financiera con la que ten\u00eda que lidiar, sino tambi\u00e9n por la situaci\u00f3n pol\u00edtica.<\/p>\n<p><strong>\u00bfC\u00f3mo fue para ti ese comienzo?<\/strong><\/p>\n<p>Fue un per\u00edodo muy intenso. En ese momento empezamos a pensar en c\u00f3mo deb\u00edamos adaptar nuestro trabajo y lanzamos un gran programa a nivel nacional dirigido a ni\u00f1os y j\u00f3venes. Esto se hizo para mitigar el efecto psicol\u00f3gico que la ocupaci\u00f3n israel\u00ed estaba causando en ellos, ya que hab\u00eda demoliciones de casas, toques de queda, muchos asesinatos, invasiones de campos de refugiados, ciudades, pueblos, etc.<\/p>\n<p>As\u00ed que trabajamos con estos ni\u00f1os y las agencias comenzaron a confiar en nuestro trabajo y a financiar este proyecto. \u00a1Incluso publicamos un libro llamado\u00a0<i>Art during siege<\/i>! Hac\u00edamos talleres de teatro, danza, m\u00fasica, pintura\u2026 Sol\u00edamos ir a ciudades aisladas donde tardabas como cinco o seis horas en llegar por culpa de los checkpoints (puestos de control), solo para realizar un taller de dos horas\u2026 Pero pens\u00e1bamos que era muy importante para la comunidad y, de hecho, se convirti\u00f3 en un programa estrat\u00e9gico hasta el d\u00eda de hoy.<\/p>\n<p><strong>\u00bfQu\u00e9 importancia crees que tiene para la resistencia palestina llevar el arte y la cultura a peque\u00f1as aldeas y lugares aislados?<\/strong><\/p>\n<p>Te responder\u00e9 con un ejemplo muy claro. Antes del genocidio organizamos un festival en una aldea que est\u00e1 rodeada por tres asentamientos ilegales. Fue una actuaci\u00f3n al aire libre y los soldados israel\u00edes se acercaron a la gente y les dijeron: \u201cOye, ya sab\u00e9is aqu\u00ed tenemos algunos colonos peligrosos, as\u00ed que tened cuidado\u201d. En ese momento, les preguntamos a las vecinas si estaban seguras de querer hacer el espect\u00e1culo. Nosotros est\u00e1bamos dispuestas a realizarlo y no ten\u00edamos problema, pero no quer\u00edamos poner en riesgo sus vidas.<\/p>\n<p>Ellas respondieron que no, que eso precisamente era parte de su resistencia y de su rebeld\u00eda frente a la ocupaci\u00f3n. As\u00ed que hicimos todo el festival. Fue un desaf\u00edo y forma parte de nuestra lucha. S\u00ed, fue un reto.<\/p>\n<p>En nuestro camino de regreso pusieron muchos controles, as\u00ed que tuvimos que dar un rodeo de aproximadamente dos horas para salir de la aldea. Por supuesto, los israel\u00edes siempre han visto el arte y la cultura palestina como una amenaza.<\/p>\n<p><strong>Has mencionado antes la importancia de la comunidad y sabemos que en Palestina, principalmente debido al aislamiento que impone el ej\u00e9rcito israel\u00ed, las comunidades son muy diversas y cada una tiene sus peculiaridades \u00bfC\u00f3mo trabaja el Popular Art Centre con la idiosincrasia de cada peque\u00f1a comunidad?<\/strong><\/p>\n<p>Desde la \u00e9poca de la Segunda Intifada, pensamos que parte de nuestra misi\u00f3n era construir alianzas. No necesitamos establecer sucursales del Popular Art Centre en aldeas, ciudades o campos de refugiados, porque los socios que trabajan all\u00ed ya comparten nuestra visi\u00f3n y son quienes deben ser empoderados para trabajar con sus comunidades locales. Juntos construimos un n\u00facleo cultural y social en diferentes partes de Palestina.<\/p>\n<p>Nosotros sabemos que cada lugar al que vamos tiene sus propios problemas internos. Hay lugares que son un poco conservadores, pero sin embargo, todos saben que nosotros s\u00f3lo hacemos actividades si el servicio se ofrece tanto a hombres como a mujeres.<\/p>\n<p><strong>\u00bfY c\u00f3mo gestion\u00e1is esta situaci\u00f3n desde el Popular Art Centre?<\/strong><\/p>\n<p>Cuando les resulta dif\u00edcil mezclar a ni\u00f1os y ni\u00f1as, les decimos:\u00a0\u201cEst\u00e1 bien, les daremos actividades por separado\u2026 Hasta que las cosas maduren lo suficiente para que podamos tenerlos juntos y trabajar juntos\u201d. A veces, en el dabke (danza tradicional palestina), tomarse de las manos entre ni\u00f1os y ni\u00f1as o mujeres y hombres no es f\u00e1cil para ellos. As\u00ed que siempre acordamos con el centro local ir paso a paso.<\/p>\n<p>Sabemos que podemos lograr el objetivo que queremos, pero lo que no puedes hacer es salir de la nada diciendo: \u201cAh, queremos que todos particip\u00e9is y lo hag\u00e1is de esta forma\u201d. No. Debemos trabajar con la comunidad, paso a paso. Y porque somos parte de ella, sabemos c\u00f3mo deben hacerse las cosas y qu\u00e9 se necesita en cada momento.<\/p>\n<p>Una vez construimos estas alianzas, trabajamos a trav\u00e9s de ellas. Trabajamos juntos, planificamos actividades juntos\u2026 No es que les digamos qu\u00e9 hacer o qu\u00e9 no hacer, es un trabajo mutuo y hay un respeto mutuo por el trabajo de cada uno.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-first\" style=\"--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-bg-size:cover;--awb-margin-bottom:30px;width:48%; margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1920\" height=\"1280\" alt=\"Entrevista a la activista Iman Hammouri\" title=\"454912873_913570830809298_218783645063056000_n-2 copia\" src=\"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/454912873_913570830809298_218783645063056000_n-2-copia-scaled.jpg\" class=\"img-responsive wp-image-25901\" srcset=\"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/454912873_913570830809298_218783645063056000_n-2-copia-200x133.jpg 200w, https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/454912873_913570830809298_218783645063056000_n-2-copia-400x267.jpg 400w, https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/454912873_913570830809298_218783645063056000_n-2-copia-600x400.jpg 600w, https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/454912873_913570830809298_218783645063056000_n-2-copia-800x533.jpg 800w, https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/454912873_913570830809298_218783645063056000_n-2-copia-1200x800.jpg 1200w, https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/454912873_913570830809298_218783645063056000_n-2-copia-scaled.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/span><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;width:48%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-2\" style=\"--awb-text-transform:none;\"><p><strong>Con la situaci\u00f3n actual \u00bfCu\u00e1l crees que es la principal tarea del Popular Art Centre ahora mismo?<\/strong><\/p>\n<p>Ahora, durante el genocidio, creemos que el arte y la cultura no est\u00e1n separados de nuestra situaci\u00f3n pol\u00edtica, ni de nuestra situaci\u00f3n social y econ\u00f3mica. Creemos que el arte y la cultura deben ser un reflejo de lo que estamos viviendo. Por ejemplo, deben reflejar nuestros miedos, esperanzas, aspiraciones y sufrimientos. Para nosotros el arte es una herramienta. No es un fin en s\u00ed mismo. No trabajamos arduamente por el mero hecho de ser artistas.<\/p>\n<p>Durante el genocidio estamos trabajando especialmente en la salud psicol\u00f3gica y mental de los ni\u00f1os junto con nuestros socios en Gaza. Organizamos talleres de danza y teatro, para que al menos haya una salida segura para ellos.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:10px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-3\" style=\"--awb-text-transform:none;\"><p>Nuestros maestros, artistas y socios tienen una energ\u00eda adicional, incluso bajo el fuego y las bombas. Ellos siempre est\u00e1n listos y nos dicen:\u00a0\u201cpor favor, queremos hacer algo\u201d. As\u00ed que simplemente nos indican lo que se necesita y d\u00f3nde.<\/p>\n<p>\u00daltimamente nos piden que hagamos las actividades en el norte de la Franja de Gaza, ya que el ej\u00e9rcito israel\u00ed quiere evacuar a la poblaci\u00f3n de esa zona mediante bombardeos y asesinatos, para posteriormente ocuparla y anexionarla. Pero hay algunas personas que est\u00e1n resistiendo y se est\u00e1n quedando en sus casas, as\u00ed que debemos hacerlo por ellos. Es una forma de no rendirse.<\/p>\n<p><strong>En este contexto donde la poblaci\u00f3n no tiene acceso a las necesidades b\u00e1sicas en cuanto a salud, alimentaci\u00f3n, seguridad, etc. \u00bfC\u00f3mo logr\u00e1is concienciar a la poblaci\u00f3n sobre la importancia de mantener la actividad art\u00edstica y cultural?<\/strong><\/p>\n<p>Porque nosotros trabajamos en ambas cosas, creemos que no tiene sentido separar una cosa de la otra. Trabajamos tanto en ayuda humanitaria como en programas de salud psicol\u00f3gica y mental a trav\u00e9s de talleres art\u00edsticos. Pero siempre siempre desde las prioridades de nuestros socios en terreno, as\u00ed que si ellos no consideran necesaria una intervenci\u00f3n, simplemente no la realizamos.<\/p>\n<p>Sin embargo, lo que nos dicen ahora mismo desde Gaza es que es m\u00e1s importante que nunca continuar con nuestras actividades. Debemos persistir, debemos tener esperanza y seguir organizando actividades creativas que permitan a los ni\u00f1os y j\u00f3venes mantener la esperanza y contar con salidas seguras; a ellos les encanta formar parte de estas actividades.<\/p>\n<p><strong>En cuanto a los artistas \u00bfCu\u00e1les son las principales dificultades que est\u00e1n enfrentando ahora mismo en Palestina?<\/strong><\/p>\n<p>La situaci\u00f3n es m\u00e1s cr\u00edtica que nunca. En Gaza hay artistas que han sido asesinados, algunos han sido encarcelados, otros han resultado heridos y algunos han tenido que abandonar el pa\u00eds para salvar sus vidas. Adem\u00e1s, muchos artistas visuales que todav\u00eda est\u00e1n all\u00ed han visto como todas sus obras han sido destruidas. As\u00ed que todo su tesoro y su medio de vida ha sido aniquilado.<\/p>\n<p>Pero no solo en Gaza; para nosotros, en Cisjordania, las cosas tambi\u00e9n se est\u00e1n volviendo muy dif\u00edciles. En el norte, especialmente en Jenin, Tulkarem, Nablus, etc., est\u00e1n invadiendo ciudades, aldeas y campos de refugiados todos los d\u00edas. Y no solo eso, tambi\u00e9n est\u00e1n invadiendo centros art\u00edsticos y culturales. Por ejemplo, invadieron el teatro de uno de nuestros socios mientras los ni\u00f1os estaban all\u00ed, lo que les caus\u00f3 much\u00edsimo miedo. Cada d\u00eda hay miedo y siempre se presencia la invasi\u00f3n.<\/p>\n<p>La restricci\u00f3n de movimiento tambi\u00e9n es uno de los principales problemas. No es seguro desplazarse. Nosotros trabajamos a nivel nacional y no queremos poner en peligro la vida de nadie. Estos meses hemos visto a colonos atacando casi a diario en las carreteras, agrediendo a palestinos mientras viajan, etc.<\/p>\n<p><strong>\u00bfC\u00f3mo se intentan mitigar, en la medida de lo posible, estas dificultades desde el sector art\u00edstico y cultural?<\/strong><\/p>\n<p>La verdad es que hemos creado una red de solidaridad muy importante. Respecto a lo que comentaba sobre los artistas visuales, desde el sector del arte ahora estamos tratando de ayudar a aquellos artistas que a\u00fan tienen algunas obras, para que puedan venderlas en el exterior y as\u00ed obtener algo de dinero.<\/p>\n<p>En cuanto a los artistas esc\u00e9nicos, ellos est\u00e1n creando producciones que reflejan todo lo que est\u00e1 sucediendo. Nosotros tomamos estas producciones y las acercamos a la gente, al p\u00fablico en general, adem\u00e1s de apoyarles en su producci\u00f3n. Por otro lado, en Cisjordania tambi\u00e9n estamos realizando algunas presentaciones y espect\u00e1culos para recaudar fondos para la gente en Gaza.<\/p>\n<p><strong>\u00bfCrees que la persecuci\u00f3n del arte y la cultura palestina ha sido una de las prioridades de la ocupaci\u00f3n israel\u00ed a lo largo de la historia?<\/strong><\/p>\n<p>No es que lo crea, es que es algo expl\u00edcito. Cuando comenzamos en 1987, nuestra misi\u00f3n principal era preservar nuestra identidad palestina, no solo nuestra cultura y el patrimonio, porque en ese momento estaban prohibidos la danza, la m\u00fasica e incluso dibujar los colores de la bandera. Los artistas eran arrestados por ello. Quer\u00edan robar nuestro patrimonio, y han estado haci\u00e9ndolo hasta hoy.<\/p>\n<p>Ellos quieren apropiarse de las costumbres palestinas, afirman que la comida tradicional palestina, o incluso la comida \u00e1rabe, les pertenece. Tambi\u00e9n dicen que la danza tradicional palestina es su danza\u2026 Esto tiene una explicaci\u00f3n muy sencilla, el estado sionista quiere mostrar que la tierra que est\u00e1n ocupando es una tierra sin patrimonio. Por eso nunca se detendr\u00e1n. Para ellos, que exista una herencia cultural es una amenaza y un obst\u00e1culo.<\/p>\n<p><strong>Cuando visitas los campos de refugiadas palestinas en el L\u00edbano o en Jordania, en seguida te das cuenta de la importancia que tiene la cultura y el arte palestino en las vidas de las personas. \u00bfPor qu\u00e9 motivo crees que la herencia cultural Palestina es tan fuerte en aquellas personas que viven en la di\u00e1spora?<\/strong><\/p>\n<p>Creo que es algo particular de los palestinos. Ellos se aferran a su herencia cultural, ya que es de las pocas conexiones que tienen con su origen.<\/p>\n<p>Como mencion\u00e9 antes, tambi\u00e9n sienten la amenaza de la ocupaci\u00f3n israel\u00ed que intenta robar su patrimonio. Por eso, la gente siente un gran orgullo, especialmente aquellos refugiados que fueron expulsados de Palestina y se encuentran en la di\u00e1spora.<\/p>\n<p><strong>En tu opini\u00f3n \u00bfCu\u00e1l es el futuro de esta herencia?<\/strong><\/p>\n<p>Nosotros no queremos que el patrimonio quede solo en manos de los mayores, tambi\u00e9n queremos que los j\u00f3venes tomen partido y lo transmitan a la siguiente generaci\u00f3n. Por eso, en el Popular Art Centre, tenemos alrededor de 400 ni\u00f1os y ni\u00f1as matriculados en nuestra escuela de danza cada a\u00f1o.<\/p>\n<p>En 1994, nuestro grupo de danza fue a grabar una canci\u00f3n tradicional que sol\u00edamos tocar en las bodas palestinas, pero descubrimos que el creador de esa canci\u00f3n hab\u00eda fallecido. As\u00ed que surgi\u00f3 la idea de que ten\u00edamos que preservar esa m\u00fasica y transmitirla a las generaciones m\u00e1s j\u00f3venes. Ahora tenemos un archivo con m\u00e1s de 200 horas de grabaciones de m\u00fasica tradicional.<\/p>\n<p>Adem\u00e1s, en el a\u00f1o 2020, durante la pandemia, fuimos a grabar canciones tradicionales con mujeres y hombres para realmente expandir nuestra colecci\u00f3n y aumentar la riqueza de nuestro archivo audiovisual.<\/p>\n<p><strong>Esta semana has estado en Barcelona invitada por la Associaci\u00f3 Catalana per la Pau y has podido reunirte con instituciones, entidades culturales y organizaciones diversas \u00bfC\u00f3mo de importante crees que es este intercambio cultural?<\/strong><\/p>\n<p>Algunas personas suelen preguntarme: \u00bfVale la pena viajar al extranjero en estos momentos? \u00bfAcaso mejorar\u00e1 nuestra situaci\u00f3n? Para m\u00ed, es m\u00e1s importante que nunca.<\/p>\n<p>Al final, lo que pretende la ocupaci\u00f3n israel\u00ed es que nos quedemos aislados, no quieren que otras culturas se introduzcan en la cultura palestina, ni que nosotros seamos introducidos en otras culturas. Desde el origen del Popular Art Centre, cuando lanzamos el Palestinian International Festival, una de nuestras misiones principales ha sido construir puentes y mostrar estos puntos en com\u00fan con otras culturas, como en este caso con la catalana.<\/p>\n<p>Por tanto, ha sido una visita muy gratificante; tanto por ver el apoyo de la sociedad a la causa palestina como por las futuras colaboraciones que puedan surgir a partir de ahora.<\/p>\n<p><strong>El pasado fin de semana hab\u00e9is estado en la Fira Mediterr\u00e1nia de Manresa donde el bailar\u00edn y core\u00f3grafo del Popular Art Centre, Sharaf Darzaid, realiz\u00f3 dos funciones de su espect\u00e1culo \u201cLove in Times of Apartheid\u201d. \u00bfC\u00f3mo viviste esa experiencia?<\/strong><\/p>\n<p>Para nosotros, este intercambio y colaboraci\u00f3n es muy importante. A trav\u00e9s de la pieza de danza \u201cLove in Times of the Apartheid\u201d, Sharaf muestra el sufrimiento y las dificultades de amar bajo la ocupaci\u00f3n israel\u00ed. Esto permite que mucha gente se aproxime a la causa palestina a trav\u00e9s del arte. De hecho, al final del espect\u00e1culo muchas personas se aproximaron y nos dijeron que se sintieron conmovidas. Fue muy emocionante.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-first\" style=\"--awb-bg-size:cover;--awb-margin-bottom:10px;width:48%; margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-margin-bottom:3%;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"1920\" height=\"1282\" alt=\"Entrevista a l&#039;activista social i cultural Iman Hammouri\" title=\"DSC_8511 copia\" src=\"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/DSC_8511-copia-scaled.jpg\" class=\"img-responsive wp-image-25903\" srcset=\"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/DSC_8511-copia-200x134.jpg 200w, https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/DSC_8511-copia-400x267.jpg 400w, https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/DSC_8511-copia-600x401.jpg 600w, https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/DSC_8511-copia-800x534.jpg 800w, https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/DSC_8511-copia-1200x801.jpg 1200w, https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/DSC_8511-copia-scaled.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/span><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-last\" style=\"--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-bg-size:cover;--awb-margin-bottom:0px;width:48%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-4\" style=\"--awb-text-transform:none;\"><p><strong>Entre todo tu trabajo como activista por los derechos culturales, tambi\u00e9n eres presidenta de la Palestinian Performing Arts Network. Expl\u00edcanos un poco en qu\u00e9 \u00e1mbitos trabaj\u00e1is en esta entidad.<\/strong><\/p>\n<p>S\u00ed, soy la presidenta de la Palestinian Performing Arts Network, que re\u00fane a 13 organizaciones de artes esc\u00e9nicas, cada una enfocada en diferentes disciplinas como danza, m\u00fasica, circo y teatro. Nos unimos para multiplicar nuestro impacto y tambi\u00e9n para alzar nuestra voz en la defensa de los derechos culturales de nuestros artistas palestinos.<\/p>\n<p>Por un lado, se trata de construir puentes con otras culturas, elevar nuestra voz y desempe\u00f1ar nuestro papel en la confrontaci\u00f3n de la ocupaci\u00f3n israel\u00ed. Pero, por otro lado, tambi\u00e9n es importante hacer lobby y abogar por nuestras cuestiones internas.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:10px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-5\" style=\"--awb-text-transform:none;\"><p>Esto implica presionar al gobierno palestino y al Ministerio de Cultura para que apoyen a los artistas palestinos, reduzcan los impuestos sobre ellos y les proporcionen m\u00e1s espacios, entre otras cosas. Es fundamental hacer lobby por nuestros derechos y encontrar apoyo financiero para las actividades art\u00edsticas.<\/p>\n<p><strong>Ya nos ha quedado claro que tanto el Popular Art Centre como t\u00fa personalmente sois incansables y no parar\u00e9is de realizar vuestros proyectos. \u00bfCu\u00e1ndo os volveremos a ver por aqu\u00ed y qu\u00e9 planes ten\u00e9is en el futuro con la Associaci\u00f3 Catalana per la Pau?<\/strong><\/p>\n<p>S\u00ed, te puedo avanzar que con la<a href=\"https:\/\/acpau.org\/es\/\" target=\"_blank\" rel=\"noopener\"> Associaci\u00f3 Catalana per la Pau<\/a> tenemos un proyecto entre manos para los pr\u00f3ximos meses llamado \u201cSom Constructores\u201d.<\/p>\n<p>El pasado jueves, mi compa\u00f1ero Sharaf dio una clase magistral de danza en Granollers (Barcelona). A partir de esta clase, seleccionar\u00e1 un grupo de bailarines y estos trabajar\u00e1n en un espect\u00e1culo conjunto con otros bailarines palestinos del Popular Art Centre. Por supuesto, vendremos en diciembre para continuar con esta creaci\u00f3n y se har\u00e1n funciones en Catalu\u00f1a. Inicialmente, la idea del proyecto tambi\u00e9n era hacer otra representaci\u00f3n con el mismo grupo en Palestina, pero ser\u00e1 dif\u00edcil\u2026 Si la situaci\u00f3n lo permite, nos encantar\u00eda hacerlo all\u00ed.<\/p>\n<p><strong>Ojal\u00e1.<\/strong><\/p>\n<p>Inshallah.<\/p>\n<p><em>Este art\u00edculo se public\u00f3 originalmente en\u00a0<a href=\"https:\/\/osalto.gal\/palestina\/gaza-aun-organizamos-actividades-artisticas-ninas-jovenes-puedan-contar-un-espacio-seguro\" target=\"_blank\" rel=\"noopener\">El Salto Diario<\/a>.<\/em><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:30px;--awb-padding-right:0px;--awb-padding-bottom:0px;--awb-padding-left:0px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-background-color:#cceff8;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_5 1_5 fusion-one-fifth fusion-column-first\" style=\"--awb-bg-size:cover;width:20%;width:calc(20% - ( ( 4% + 4% ) * 0.2 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_3_5 3_5 fusion-three-fifth\" style=\"--awb-bg-size:cover;width:60%;width:calc(60% - ( ( 4% + 4% ) * 0.6 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:20px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#cceff8;border-color:#cceff8;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-6\"><h2 style=\"text-align: center;\">\u00bfQuieres recibir nuestro bolet\u00edn?<\/h2>\n<\/div><div class=\"fusion-text fusion-text-7\"><script>(function() {\n\twindow.mc4wp = window.mc4wp || {\n\t\tlisteners: [],\n\t\tforms: {\n\t\t\ton: function(evt, cb) {\n\t\t\t\twindow.mc4wp.listeners.push(\n\t\t\t\t\t{\n\t\t\t\t\t\tevent   : evt,\n\t\t\t\t\t\tcallback: cb\n\t\t\t\t\t}\n\t\t\t\t);\n\t\t\t}\n\t\t}\n\t}\n})();\n<\/script><!-- Mailchimp for WordPress v4.12.0 - https:\/\/wordpress.org\/plugins\/mailchimp-for-wp\/ --><form id=\"mc4wp-form-1\" class=\"mc4wp-form mc4wp-form-48 mc4wp-form-theme mc4wp-form-theme-blue\" method=\"post\" data-id=\"48\" data-name=\"Subscripci\u00f3 Web\" ><div class=\"mc4wp-form-fields\"><p>\t<input type=\"email\" name=\"EMAIL\" placeholder=\"e-mail\" required \/>\t<input type=\"submit\" value=\"Submit\" \/><\/p>\r\n\r\n<p>\t<label>\r\n        <input name=\"AGREE_TO_TERMS\" type=\"checkbox\" value=\"1\" required=\"\"> <a href=\"https:\/\/acpau.org\/politica-de-privacitat\/\" target=\"_blank\">I accept the privacy policy<\/a> \r\n    <\/label>\r\n<\/p><\/div><label style=\"display: none !important;\">Deja vac\u00edo este campo si eres humano: <input type=\"text\" name=\"_mc4wp_honeypot\" value=\"\" tabindex=\"-1\" autocomplete=\"off\" \/><\/label><input type=\"hidden\" name=\"_mc4wp_timestamp\" value=\"1778680048\" \/><input type=\"hidden\" name=\"_mc4wp_form_id\" value=\"48\" \/><input type=\"hidden\" name=\"_mc4wp_form_element_id\" value=\"mc4wp-form-1\" \/><div class=\"mc4wp-response\"><\/div><\/form><!-- \/ Mailchimp for WordPress Plugin -->\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_1_5 1_5 fusion-one-fifth fusion-column-last\" style=\"--awb-bg-size:cover;width:20%;width:calc(20% - ( ( 4% + 4% ) * 0.2 ) );\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Activista social y defensora de los derechos culturales, la directora del Popular Art Centre (Ramallah, Palestina), Iman Hammouri, es tambi\u00e9n cofundadora de la Palestinian Performing Arts Network.<\/p>\n","protected":false},"author":2,"featured_media":25898,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[135],"tags":[],"class_list":["post-25909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrevista a la activista Iman Hammouri<\/title>\n<meta name=\"description\" content=\"Entrevista a la activista Iman Hammouri, defensora dels drets culturals i directora del Popular Art Centre (Ramallah, Palestina).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista a la activista Iman Hammouri\" \/>\n<meta property=\"og:description\" content=\"Entrevista a la activista Iman Hammouri, defensora dels drets culturals i directora del Popular Art Centre (Ramallah, Palestina).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/\" \/>\n<meta property=\"og:site_name\" content=\"Associaci\u00f3 Catalana per la Pau\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-05T10:44:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-04T17:44:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/20241016-20241016_122848-copia-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rebeca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rebeca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/\"},\"author\":{\"name\":\"Rebeca\",\"@id\":\"https:\/\/acpau.org\/#\/schema\/person\/5c3237e5e1417226f013c15477007c19\"},\"headline\":\"\u201cEn Gaza a\u00fan organizamos actividades art\u00edsticas para que ni\u00f1as y j\u00f3venes puedan contar con un espacio seguro\u201d\",\"datePublished\":\"2025-06-05T10:44:39+00:00\",\"dateModified\":\"2026-04-04T17:44:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/\"},\"wordCount\":5676,\"publisher\":{\"@id\":\"https:\/\/acpau.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/20241016-20241016_122848-copia-scaled.jpg\",\"articleSection\":[\"Art\u00edculos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/\",\"url\":\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/\",\"name\":\"Entrevista a la activista Iman Hammouri\",\"isPartOf\":{\"@id\":\"https:\/\/acpau.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/20241016-20241016_122848-copia-scaled.jpg\",\"datePublished\":\"2025-06-05T10:44:39+00:00\",\"dateModified\":\"2026-04-04T17:44:51+00:00\",\"description\":\"Entrevista a la activista Iman Hammouri, defensora dels drets culturals i directora del Popular Art Centre (Ramallah, Palestina).\",\"breadcrumb\":{\"@id\":\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#primaryimage\",\"url\":\"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/20241016-20241016_122848-copia-scaled.jpg\",\"contentUrl\":\"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/20241016-20241016_122848-copia-scaled.jpg\",\"width\":1920,\"height\":1281,\"caption\":\"Entrevista a la activista Iman Hammouri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/acpau.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cEn Gaza a\u00fan organizamos actividades art\u00edsticas para que ni\u00f1as y j\u00f3venes puedan contar con un espacio seguro\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acpau.org\/#website\",\"url\":\"https:\/\/acpau.org\/\",\"name\":\"Associaci\u00f3 Catalana per la Pau\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/acpau.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acpau.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/acpau.org\/#organization\",\"name\":\"Associaci\u00f3 Catalana per la Pau\",\"url\":\"https:\/\/acpau.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/acpau.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/acpau.org\/wp-content\/uploads\/2019\/09\/logocomprovant.png\",\"contentUrl\":\"https:\/\/acpau.org\/wp-content\/uploads\/2019\/09\/logocomprovant.png\",\"width\":300,\"height\":95,\"caption\":\"Associaci\u00f3 Catalana per la Pau\"},\"image\":{\"@id\":\"https:\/\/acpau.org\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/acpau.org\/#\/schema\/person\/5c3237e5e1417226f013c15477007c19\",\"name\":\"Rebeca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/c51bd0c67bbbd6cd44e908f15b94469a75b8cde4ac162b1f0ac29de115d970a2?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c51bd0c67bbbd6cd44e908f15b94469a75b8cde4ac162b1f0ac29de115d970a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c51bd0c67bbbd6cd44e908f15b94469a75b8cde4ac162b1f0ac29de115d970a2?s=96&d=mm&r=g\",\"caption\":\"Rebeca\"},\"url\":\"https:\/\/acpau.org\/es\/author\/rebeca\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista a la activista Iman Hammouri","description":"Entrevista a la activista Iman Hammouri, defensora dels drets culturals i directora del Popular Art Centre (Ramallah, Palestina).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevista a la activista Iman Hammouri","og_description":"Entrevista a la activista Iman Hammouri, defensora dels drets culturals i directora del Popular Art Centre (Ramallah, Palestina).","og_url":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/","og_site_name":"Associaci\u00f3 Catalana per la Pau","article_published_time":"2025-06-05T10:44:39+00:00","article_modified_time":"2026-04-04T17:44:51+00:00","og_image":[{"width":1920,"height":1281,"url":"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/20241016-20241016_122848-copia-scaled.jpg","type":"image\/jpeg"}],"author":"Rebeca","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rebeca","Tiempo de lectura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#article","isPartOf":{"@id":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/"},"author":{"name":"Rebeca","@id":"https:\/\/acpau.org\/#\/schema\/person\/5c3237e5e1417226f013c15477007c19"},"headline":"\u201cEn Gaza a\u00fan organizamos actividades art\u00edsticas para que ni\u00f1as y j\u00f3venes puedan contar con un espacio seguro\u201d","datePublished":"2025-06-05T10:44:39+00:00","dateModified":"2026-04-04T17:44:51+00:00","mainEntityOfPage":{"@id":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/"},"wordCount":5676,"publisher":{"@id":"https:\/\/acpau.org\/#organization"},"image":{"@id":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#primaryimage"},"thumbnailUrl":"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/20241016-20241016_122848-copia-scaled.jpg","articleSection":["Art\u00edculos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/","url":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/","name":"Entrevista a la activista Iman Hammouri","isPartOf":{"@id":"https:\/\/acpau.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#primaryimage"},"image":{"@id":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#primaryimage"},"thumbnailUrl":"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/20241016-20241016_122848-copia-scaled.jpg","datePublished":"2025-06-05T10:44:39+00:00","dateModified":"2026-04-04T17:44:51+00:00","description":"Entrevista a la activista Iman Hammouri, defensora dels drets culturals i directora del Popular Art Centre (Ramallah, Palestina).","breadcrumb":{"@id":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#primaryimage","url":"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/20241016-20241016_122848-copia-scaled.jpg","contentUrl":"https:\/\/acpau.org\/wp-content\/uploads\/2025\/06\/20241016-20241016_122848-copia-scaled.jpg","width":1920,"height":1281,"caption":"Entrevista a la activista Iman Hammouri"},{"@type":"BreadcrumbList","@id":"https:\/\/acpau.org\/es\/entrevista-a-la-activista-iman-hammouri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/acpau.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u201cEn Gaza a\u00fan organizamos actividades art\u00edsticas para que ni\u00f1as y j\u00f3venes puedan contar con un espacio seguro\u201d"}]},{"@type":"WebSite","@id":"https:\/\/acpau.org\/#website","url":"https:\/\/acpau.org\/","name":"Associaci\u00f3 Catalana per la Pau","description":"","publisher":{"@id":"https:\/\/acpau.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acpau.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acpau.org\/#organization","name":"Associaci\u00f3 Catalana per la Pau","url":"https:\/\/acpau.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acpau.org\/#\/schema\/logo\/image\/","url":"https:\/\/acpau.org\/wp-content\/uploads\/2019\/09\/logocomprovant.png","contentUrl":"https:\/\/acpau.org\/wp-content\/uploads\/2019\/09\/logocomprovant.png","width":300,"height":95,"caption":"Associaci\u00f3 Catalana per la Pau"},"image":{"@id":"https:\/\/acpau.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/acpau.org\/#\/schema\/person\/5c3237e5e1417226f013c15477007c19","name":"Rebeca","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c51bd0c67bbbd6cd44e908f15b94469a75b8cde4ac162b1f0ac29de115d970a2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c51bd0c67bbbd6cd44e908f15b94469a75b8cde4ac162b1f0ac29de115d970a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c51bd0c67bbbd6cd44e908f15b94469a75b8cde4ac162b1f0ac29de115d970a2?s=96&d=mm&r=g","caption":"Rebeca"},"url":"https:\/\/acpau.org\/es\/author\/rebeca\/"}]}},"_links":{"self":[{"href":"https:\/\/acpau.org\/es\/wp-json\/wp\/v2\/posts\/25909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acpau.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acpau.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acpau.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acpau.org\/es\/wp-json\/wp\/v2\/comments?post=25909"}],"version-history":[{"count":15,"href":"https:\/\/acpau.org\/es\/wp-json\/wp\/v2\/posts\/25909\/revisions"}],"predecessor-version":[{"id":27468,"href":"https:\/\/acpau.org\/es\/wp-json\/wp\/v2\/posts\/25909\/revisions\/27468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acpau.org\/es\/wp-json\/wp\/v2\/media\/25898"}],"wp:attachment":[{"href":"https:\/\/acpau.org\/es\/wp-json\/wp\/v2\/media?parent=25909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acpau.org\/es\/wp-json\/wp\/v2\/categories?post=25909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acpau.org\/es\/wp-json\/wp\/v2\/tags?post=25909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}